{"id":38366,"date":"2016-10-18T10:41:36","date_gmt":"2016-10-18T02:41:36","guid":{"rendered":"https:\/\/www.flyroyalbrunei.com\/peoples-republic-china\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/"},"modified":"2016-10-18T10:41:36","modified_gmt":"2016-10-18T02:41:36","slug":"samsung-galaxy-note-7-prohibited-on-all-rb-flights","status":"publish","type":"post","link":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/","title":{"rendered":"Samsung Galaxy Note 7 prohibited on all RB flights"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Effective 18 October 2016, Royal Brunei Airlines (RB) has prohibited the carriage of Samsung Galaxy Note 7 on all RB flights in accordance with the Brunei Department of Civil Aviation Security Notice dated 17th October 2016 which bans the carriage of Samsung Galaxy Note 7 on board all flights.<\/p>\n<p>As a safety and precautionary measure, the prohibition applies to Samsung Galaxy Note 7 devices that are carried onto the aircraft in person, carry-on baggage, checked-in luggage and cargo.<\/p>\n<p>Passengers are advised that anyone found in possession of the Samsung Galaxy Note 7 will be denied boarding.<\/p>\n<p>RB\u2019s utmost priority is the safety of its crew and valuable passengers.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Effective 18 October 2016, Royal Brunei Airlines (RB) has prohibited the carriage of Samsung Galaxy Note 7 on all RB flights in accordance with the Brunei Department of Civil Aviation Security Notice..<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[148,146],"tags":[],"class_list":["post-38366","post","type-post","status-publish","format-standard","hentry","category-travel-advisory-zh","category-uncategorized-zh","post-single border-bottom"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Samsung Galaxy Note 7 prohibited on all RB flights - China<\/title>\n<meta name=\"description\" content=\"Samsung Galaxy Note 7 prohibited on all RB flights. Stay informed about safety regulations and updates.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Samsung Galaxy Note 7 prohibited on all RB flights - China\" \/>\n<meta property=\"og:description\" content=\"Samsung Galaxy Note 7 prohibited on all RB flights. Stay informed about safety regulations and updates.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/\" \/>\n<meta property=\"og:site_name\" content=\"China\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-18T02:41:36+00:00\" \/>\n<meta name=\"author\" content=\"manager_air\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"manager_air\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/zh\\\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/zh\\\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\\\/\"},\"author\":{\"name\":\"manager_air\",\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/en\\\/#\\\/schema\\\/person\\\/d19a4e157e2463edadfe36d16c3b48be\"},\"headline\":\"Samsung Galaxy Note 7 prohibited on all RB flights\",\"datePublished\":\"2016-10-18T02:41:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/zh\\\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\\\/\"},\"wordCount\":124,\"articleSection\":[\"Travel Advisory\",\"Uncategorized @zh\"],\"inLanguage\":\"zh-CH\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/zh\\\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\\\/\",\"url\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/zh\\\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\\\/\",\"name\":\"Samsung Galaxy Note 7 prohibited on all RB flights - China\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/en\\\/#website\"},\"datePublished\":\"2016-10-18T02:41:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/en\\\/#\\\/schema\\\/person\\\/d19a4e157e2463edadfe36d16c3b48be\"},\"description\":\"Samsung Galaxy Note 7 prohibited on all RB flights. Stay informed about safety regulations and updates.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/zh\\\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\\\/#breadcrumb\"},\"inLanguage\":\"zh-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/zh\\\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/zh\\\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/zh\\\/home-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Samsung Galaxy Note 7 prohibited on all RB flights\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/en\\\/\",\"name\":\"China\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/en\\\/#\\\/schema\\\/person\\\/d19a4e157e2463edadfe36d16c3b48be\",\"name\":\"manager_air\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fccaaf001fe8198772bf5e5efee8c61628fc21b6269e82041101db54016e670e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fccaaf001fe8198772bf5e5efee8c61628fc21b6269e82041101db54016e670e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fccaaf001fe8198772bf5e5efee8c61628fc21b6269e82041101db54016e670e?s=96&d=mm&r=g\",\"caption\":\"manager_air\"},\"url\":\"https:\\\/\\\/www.flyroyalbrunei.com\\\/china\\\/zh\\\/author\\\/manager_air\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Samsung Galaxy Note 7 prohibited on all RB flights - China","description":"Samsung Galaxy Note 7 prohibited on all RB flights. Stay informed about safety regulations and updates.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Samsung Galaxy Note 7 prohibited on all RB flights - China","og_description":"Samsung Galaxy Note 7 prohibited on all RB flights. Stay informed about safety regulations and updates.","og_url":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/","og_site_name":"China","article_published_time":"2016-10-18T02:41:36+00:00","author":"manager_air","twitter_card":"summary_large_image","twitter_misc":{"Written by":"manager_air","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/#article","isPartOf":{"@id":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/"},"author":{"name":"manager_air","@id":"https:\/\/www.flyroyalbrunei.com\/china\/en\/#\/schema\/person\/d19a4e157e2463edadfe36d16c3b48be"},"headline":"Samsung Galaxy Note 7 prohibited on all RB flights","datePublished":"2016-10-18T02:41:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/"},"wordCount":124,"articleSection":["Travel Advisory","Uncategorized @zh"],"inLanguage":"zh-CH"},{"@type":"WebPage","@id":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/","url":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/","name":"Samsung Galaxy Note 7 prohibited on all RB flights - China","isPartOf":{"@id":"https:\/\/www.flyroyalbrunei.com\/china\/en\/#website"},"datePublished":"2016-10-18T02:41:36+00:00","author":{"@id":"https:\/\/www.flyroyalbrunei.com\/china\/en\/#\/schema\/person\/d19a4e157e2463edadfe36d16c3b48be"},"description":"Samsung Galaxy Note 7 prohibited on all RB flights. Stay informed about safety regulations and updates.","breadcrumb":{"@id":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/#breadcrumb"},"inLanguage":"zh-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/samsung-galaxy-note-7-prohibited-on-all-rb-flights\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/home-2\/"},{"@type":"ListItem","position":2,"name":"Samsung Galaxy Note 7 prohibited on all RB flights"}]},{"@type":"WebSite","@id":"https:\/\/www.flyroyalbrunei.com\/china\/en\/#website","url":"https:\/\/www.flyroyalbrunei.com\/china\/en\/","name":"China","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.flyroyalbrunei.com\/china\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-CH"},{"@type":"Person","@id":"https:\/\/www.flyroyalbrunei.com\/china\/en\/#\/schema\/person\/d19a4e157e2463edadfe36d16c3b48be","name":"manager_air","image":{"@type":"ImageObject","inLanguage":"zh-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/fccaaf001fe8198772bf5e5efee8c61628fc21b6269e82041101db54016e670e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fccaaf001fe8198772bf5e5efee8c61628fc21b6269e82041101db54016e670e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fccaaf001fe8198772bf5e5efee8c61628fc21b6269e82041101db54016e670e?s=96&d=mm&r=g","caption":"manager_air"},"url":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/author\/manager_air\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/wp-json\/wp\/v2\/posts\/38366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/wp-json\/wp\/v2\/comments?post=38366"}],"version-history":[{"count":0,"href":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/wp-json\/wp\/v2\/posts\/38366\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/wp-json\/wp\/v2\/media?parent=38366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/wp-json\/wp\/v2\/categories?post=38366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.flyroyalbrunei.com\/china\/zh\/wp-json\/wp\/v2\/tags?post=38366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}